{"id":5384,"date":"2025-12-08T09:41:59","date_gmt":"2025-12-08T15:41:59","guid":{"rendered":"https:\/\/lamexicanasupermercado.com\/?post_type=product&#038;p=5384"},"modified":"2026-02-21T20:57:16","modified_gmt":"2026-02-22T02:57:16","slug":"queso-panela-el-mexicano","status":"publish","type":"product","link":"https:\/\/lamexicanasupermercado.com\/en\/product\/queso-panela-el-mexicano\/","title":{"rendered":"Queso Panela El Mexicano"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Queso Panela El Mexicano, Carniceria<\/p>","protected":false},"featured_media":5396,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"product_brand":[],"product_cat":[843],"product_tag":[1170,541,468],"class_list":["post-5384","product","type-product","status-publish","has-post-thumbnail","product_cat-carniceria","product_tag-carne","product_tag-meat","product_tag-queso","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product\/5384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/comments?post=5384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/media\/5396"}],"wp:attachment":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/media?parent=5384"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_brand?post=5384"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_cat?post=5384"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_tag?post=5384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}