{"id":4265,"date":"2025-11-28T00:32:13","date_gmt":"2025-11-28T00:32:13","guid":{"rendered":"https:\/\/lamexicanasupermercado.com\/product\/leche-2-1-gal\/"},"modified":"2026-02-21T20:46:37","modified_gmt":"2026-02-22T02:46:37","slug":"leche-2-1-gal","status":"publish","type":"product","link":"https:\/\/lamexicanasupermercado.com\/en\/product\/leche-2-1-gal\/","title":{"rendered":"Leche 2% 1 Gal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Leche 2%<\/p>","protected":false},"featured_media":4390,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"product_brand":[],"product_cat":[1061],"product_tag":[1066,1065,238,587],"class_list":["post-4265","product","type-product","status-publish","has-post-thumbnail","product_cat-lacteo","product_tag-almuerzo","product_tag-breakfast","product_tag-leche","product_tag-milk","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product\/4265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/comments?post=4265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/media\/4390"}],"wp:attachment":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/media?parent=4265"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_brand?post=4265"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_cat?post=4265"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_tag?post=4265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}