{"id":2476,"date":"2025-11-06T02:13:07","date_gmt":"2025-11-06T02:13:07","guid":{"rendered":"https:\/\/lamexicanasupermercado.com\/product\/nestle-nido-kinder-1-12-6-oz\/"},"modified":"2026-03-28T18:58:24","modified_gmt":"2026-03-29T00:58:24","slug":"nestle-nido-kinder-1-12-6-oz","status":"publish","type":"product","link":"https:\/\/lamexicanasupermercado.com\/en\/product\/nestle-nido-kinder-1-12-6-oz\/","title":{"rendered":"Nestle Nido Kinder 1+ 12.6 oz"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Nestle Nido Kinder 1+ 12.6 oz<\/p>","protected":false},"featured_media":3039,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"product_brand":[34],"product_cat":[667],"product_tag":[238],"class_list":["post-2476","product","type-product","status-publish","has-post-thumbnail","product_brand-nestle","product_cat-lacteos","product_tag-leche","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product\/2476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/comments?post=2476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/media\/3039"}],"wp:attachment":[{"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/media?parent=2476"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_brand?post=2476"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_cat?post=2476"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamexicanasupermercado.com\/en\/wp-json\/wp\/v2\/product_tag?post=2476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}